{"id":710,"date":"2020-06-18T12:12:28","date_gmt":"2020-06-18T12:12:28","guid":{"rendered":"https:\/\/garciamariformacion.com\/?page_id=710"},"modified":"2021-05-17T16:04:38","modified_gmt":"2021-05-17T16:04:38","slug":"cad-cam","status":"publish","type":"page","link":"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/","title":{"rendered":"Cours intensif en implants dentaires, chirurgie guid\u00e9e par ordinateur et conception CAD-CAM"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"710\" class=\"elementor elementor-710\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f659f50 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f659f50\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-1339d86\" data-id=\"1339d86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c4c2b9 elementor-widget elementor-widget-heading\" data-id=\"2c4c2b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cours intensif avec des patients :<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87ba697 elementor-widget elementor-widget-heading\" data-id=\"87ba697\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Implants dentaires, chirurgie guid\u00e9e et conception CAD-CAM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a05252 elementor-widget elementor-widget-text-editor\" data-id=\"3a05252\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\tDans ce cours \u00e9minemment pratique, nous r\u00e9aliserons le diagnostic et la planification \u00e0 l&#039;aide d&#039;outils de conception CAD-CAM. Cela nous permettra d\u2019entrer dans le monde de la chirurgie guid\u00e9e par ordinateur. Comme il s&#039;agit d&#039;un cours d&#039;introduction, des concepts tels que la mise en charge imm\u00e9diate et la gestion des tissus mous seront expliqu\u00e9s en relation avec la pose d&#039;implants dentaires, ce qui vous donnera la confiance n\u00e9cessaire pour effectuer vos premi\u00e8res interventions chirurgicales. \n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-48614c4 elementor-widget elementor-widget-text-editor\" data-id=\"48614c4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<p>Avant de commencer la pratique clinique, les participants passeront en revue la litt\u00e9rature existante dans la sp\u00e9cialit\u00e9 de la r\u00e9g\u00e9n\u00e9ration des tissus mous et des os. Ces le\u00e7ons th\u00e9oriques aideront les cliniciens \u00e0 identifier la meilleure option de traitement pour chaque cas particulier, ainsi que ses limites pour garantir le succ\u00e8s dans chaque cas.<\/p><p>Ce cours est orient\u00e9 exclusivement vers la pratique chirurgicale. L&#039;objectif est de mettre en pratique les techniques apprises. Ce cours convient \u00e0 ceux qui cherchent \u00e0 apprendre et \u00e0 d\u00e9velopper de nouvelles comp\u00e9tences, ou \u00e0 ceux qui cherchent \u00e0 affiner et d\u00e9velopper des comp\u00e9tences existantes. Diff\u00e9rents types de chirurgies bas\u00e9es sur la r\u00e9g\u00e9n\u00e9ration seront accessibles \u00e0 chaque \u00e9tudiant avec de vrais patients. Avant de r\u00e9aliser chaque technique, elle sera pratiqu\u00e9e sur des t\u00eates de porc.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d35e8ee elementor-position-left elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"d35e8ee\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span class=\"elementor-icon elementor-animation-\" >\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-graduation-cap\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t<span >Ce cours donne acc\u00e8s aux dipl\u00f4mes officiels suivants de l&#039;Universit\u00e9 CEU San Pablo\u00a0:<\/span>\n\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\"><ul>\n \t<li>Expert universitaire en implantologie orale<\/li>\n \t<li>Expert universitaire en r\u00e9g\u00e9n\u00e9ration osseuse guid\u00e9e<\/li>\n<\/ul><\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c3942a elementor-widget elementor-widget-accordion\" data-id=\"4c3942a\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7991\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-7991\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Description du cours<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7991\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7991\"><p>Le cours est orient\u00e9 exclusivement vers la pratique chirurgicale.<\/p><p>Afin de profiter au maximum des heures pratiques cliniques, avant le d\u00e9but du cours, les participants auront acc\u00e8s \u00e0 une classe virtuelle avec un contenu didactique qui expliquera les concepts les plus significatifs, pertinents et actuels du sujet.<\/p><p>Ils pourront trouver des textes, visualiser des photos et des webinaires, acc\u00e9der \u00e0 la bibliographie qui les int\u00e9resse et contacter l&#039;enseignant en cas de questions.<\/p><p>Partant de l&#039;id\u00e9e que tous les participants n&#039;ont pas les m\u00eames connaissances pr\u00e9alables, \u00e0 la fin des contenus de la classe virtuelle, il sera obligatoire de passer un examen \u00e0 choix multiples pour v\u00e9rifier l&#039;utilisation des heures th\u00e9oriques.<\/p><p>Les participants auront l&#039;occasion d&#039;apprendre \u00e0 poser un diagnostic pr\u00e9alable et \u00e0 planifier chaque cas avec les outils disponibles : tomodensitom\u00e9trie, chirurgie guid\u00e9e par ordinateur, \u00e9pilation diagnostique, diagnostic parodontal et tests g\u00e9n\u00e9tiques. Il y aura \u00e9galement une visite guid\u00e9e du concept des implants, expliquant les types d&#039;implants les plus courants, leurs avantages et inconv\u00e9nients, et comment mener \u00e0 bien le processus de pose d&#039;un implant du d\u00e9but \u00e0 la fin. Planification proth\u00e9tique depuis ses composants et la prise d&#039;empreinte jusqu&#039;aux types de proth\u00e8ses implantaires qui existent.<\/p><p>M\u00eame si elle est parfois ignor\u00e9e, il ne faut pas oublier l\u2019importance de la gestion des tissus avant ou simultan\u00e9ment \u00e0 la pose d\u2019implants dentaires. Pour cette raison, les m\u00e9decins pourront apprendre le protocole de mise en charge imm\u00e9diate, la proc\u00e9dure de soul\u00e8vement des sinus et les concepts de base en r\u00e9g\u00e9n\u00e9ration, types de r\u00e9g\u00e9n\u00e9ration et biomat\u00e9riaux. Enfin, la relation entre l&#039;implantologie et d&#039;autres sp\u00e9cialit\u00e9s sera expliqu\u00e9e, ainsi que les complications possibles en chirurgie.<\/p><p>Une fois cette partie compl\u00e9t\u00e9e, les m\u00e9decins auront le temps de d\u00e9velopper ces comp\u00e9tences et de mettre en pratique ce qu\u2019ils ont appris aupr\u00e8s de vrais patients. Nous proposons 6 jours de formation intensive, au cours desquels chaque m\u00e9decin posera un minimum d&#039;implants. Le cours est orient\u00e9 non seulement sur la pose d&#039;implants, mais plus important encore, il vise \u00e0 ce que les participants apprennent toutes les \u00e9tapes \u00e0 suivre et dans quels cas il sera n\u00e9cessaire de r\u00e9aliser une chirurgie de r\u00e9g\u00e9n\u00e9ration mucogingivale ou ROG.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7992\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"tab\" aria-controls=\"elementor-tab-content-7992\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Objectifs du cours<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7992\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7992\"><p>El objetivo es que al finalizar el mismo todos los profesionales hayan realizado por s\u00ed mismos un m\u00ednimo de cirug\u00edas guiadas y supervisadas por el Dr. Luis Garc\u00eda Mar\u00ed, lo que les dar\u00e1 seguridad para poder continuar realizando estos tratamientos en sus propias o cl\u00ednicas o en sus lieux de travail.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7993\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"tab\" aria-controls=\"elementor-tab-content-7993\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Qu&#039;est ce que ce cours inclus?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7993\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7993\"><ul><li>Tous les mat\u00e9riaux de marques premium : Alphabio, Microdent, Cytoplast, Geistlich,<br \/>Nobel, Ossix,\u2026<\/li><li>Acc\u00e8s \u00e0 une classe virtuelle avec du contenu p\u00e9dagogique.<\/li><li>S\u00e9jour de 7 nuits dans un h\u00f4tel 4 \u00e9toiles \u00e0 Santa Cruz de Tenerife \u2013 \u00e0 seulement 10 minutes \u00e0 pied de la clinique.<\/li><li>Tous les d\u00e9jeuners et d\u00eeners du dernier jour.<\/li><li>Kit d&#039;instruments de microchirurgie \u2013 cadeau pour le stagiaire.<\/li><li>10 implants, en plus des places dans le cours \u2013 cadeau pour le stagiaire<\/li><li>Bo\u00eete \u00e0 implants \u2013 cadeau pour le stagiaire.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7994\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"tab\" aria-controls=\"elementor-tab-content-7994\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Calendrier<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7994\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7994\"><p><strong>Du lundi au vendredi<\/strong><br \/>\u2013 Matin : 9h00 \u00e0 14h00<br \/>\u2013 Apr\u00e8s-midi : 16h00 \u00e0 20h00<\/p><p><strong>Samedi<\/strong><\/p><p>de 9h00 \u00e0 14h00<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7995\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"tab\" aria-controls=\"elementor-tab-content-7995\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Lieu<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-7995\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-7995\"><p><strong>CED Garc\u00eda Mar\u00ed, Santa Cruz de T\u00e9n\u00e9rife<\/strong><br \/>C\/ Prolongaci\u00f3n Ram\u00f3n y Cajal, 13, local 4<br \/>38003, Santa Cruz de T\u00e9n\u00e9rife<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-71918ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"71918ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-65ec60b\" data-id=\"65ec60b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5af074 elementor-widget elementor-widget-image\" data-id=\"b5af074\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"815\" src=\"https:\/\/garciamariformacion.com\/wp-content\/uploads\/2020\/05\/Dr-Luis-Garci\u0301a-Mari\u0301.jpg\" class=\"attachment-large size-large\" alt=\"Luis Garc\u00eda Mar\u00ed odont\u00f3logo de la Cl\u00ednica dental en Tenerife Garc\u00eda Mar\u00ed\" srcset=\"https:\/\/garciamariformacion.com\/wp-content\/uploads\/2020\/05\/Dr-Luis-Garci\u0301a-Mari\u0301.jpg 711w, https:\/\/garciamariformacion.com\/wp-content\/uploads\/2020\/05\/Dr-Luis-Garci\u0301a-Mari\u0301-262x300.jpg 262w\" sizes=\"(max-width: 711px) 100vw, 711px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-269b01e\" data-id=\"269b01e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37168d4 elementor-widget elementor-widget-heading\" data-id=\"37168d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr Luis Garc\u00eda Mari<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1fe1821 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1fe1821\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83bca55 elementor-widget elementor-widget-accordion\" data-id=\"83bca55\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1381\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1381\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Sp\u00e9cialiste des chirurgies tr\u00e8s complexes<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1381\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1381\"><ul style=\"color: #333333;\"><li>Dipl\u00f4m\u00e9 en m\u00e9decine dentaire. Universit\u00e9 de Murcie, 2002.<\/li><li>Master en Parodontie. Universit\u00e9 de Paris, 2005.<\/li><li>Sp\u00e9cialiste en Parodontie. Universit\u00e9 Ma\u00efmonides de Buenos Aires, 2006.<\/li><li>Programme de formation dentaire continue en implantologie, esth\u00e9tique et r\u00e9\u00e9ducation buccale. Universit\u00e9 de New York, 2007.<\/li><li>Sp\u00e9cialiste en chirurgie implantaire et r\u00e9\u00e9ducation. Universit\u00e9 de S\u00e9ville, 2014.<\/li><li>Expert en implants zygomatiques. Universit\u00e9 de L\u00e9rida, 2015.<\/li><li>Programme de ma\u00eetrise en chirurgie avanc\u00e9e en dentisterie implantaire r\u00e9g\u00e9n\u00e9rative Institut urbain Istvan. Universit\u00e9 de Szeged (Hongrie), 2018.<\/li><li>Conf\u00e9renci\u00e8re de nombreux cours nationaux et internationaux sur la r\u00e9g\u00e9n\u00e9ration, l&#039;utilisation des biomat\u00e9riaux et les techniques de lifting des seins.<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-050a7b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"050a7b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c52a61d\" data-id=\"c52a61d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-0e3d130\" data-id=\"0e3d130\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19a29eb elementor-widget elementor-widget-heading\" data-id=\"19a29eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dr Jos\u00e9 A. S\u00e1nchez Nicolas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae39137 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"ae39137\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c98ac7 elementor-widget elementor-widget-accordion\" data-id=\"8c98ac7\" data-element_type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-accordion\" role=\"tablist\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1471\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"tab\" aria-controls=\"elementor-tab-content-1471\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-angle-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-angle-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" href=\"\">Dipl\u00f4m\u00e9 en m\u00e9decine dentaire<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1471\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1471\"><ul style=\"color: #333333;\"><li>Dipl\u00f4m\u00e9 en m\u00e9decine dentaire. Universit\u00e9 de Murcie, 2002.<\/li><li><p><span style=\"font-weight: 400;\">Expert en Orthodontie et Orthop\u00e9die Dento-Faciale Garc\u00eda Coff\u00edn, 2004\/ 6.\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Groupe d&#039;\u00e9tude trimestriel sur l&#039;orthodontie et l&#039;orthop\u00e9die, 2007\/18.\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Cours Expert en Endodontie, Universit\u00e9 Internationale de Catalogne, 2008.\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Cours d&#039;expert en implantologie Eduardo Anitua, 2009\/10.\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Master en Implantologie Orale, Universit\u00e9 Miguel Hern\u00e1ndez de Eche, 2016\/17.\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Coordinateur du Cours Modulaire d&#039;Endodontie Moderne, Coll\u00e8ge Officiel des Dentistes de la R\u00e9gion de Murcie. 2018\/20\u00a0<\/span><\/p><\/li><li><p><span style=\"font-weight: 400;\">Conf\u00e9rencier du cours de dentisterie num\u00e9rique 3D, 2018\/20\u00a0<\/span><\/p><\/li><li><span style=\"font-weight: 400;\">Collaborateur du groupe ADA <\/span><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-ef8b94e\" data-id=\"ef8b94e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7fbee38 elementor-widget elementor-widget-heading\" data-id=\"7fbee38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nous vous enverrons plus d&#039;informations sur le cours par email et vous serez parmi les premiers inform\u00e9s de la date de la prochaine \u00e9dition.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-145572f eael-gravity-form-button-custom elementor-widget elementor-widget-eael-gravity-form\" data-id=\"145572f\" data-element_type=\"widget\" data-widget_type=\"eael-gravity-form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t            <div class=\"eael-contact-form eael-gravity-form eael-contact-form-align-default\">\n                                <script type=\"text\/javascript\">var gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,initializeOnLoaded:function(o){gform.domLoaded&&gform.scriptsLoaded?o():!gform.domLoaded&&gform.scriptsLoaded?window.addEventListener(\"DOMContentLoaded\",o):document.addEventListener(\"gform_main_scripts_loaded\",o)},hooks:{action:{},filter:{}},addAction:function(o,n,r,t){gform.addHook(\"action\",o,n,r,t)},addFilter:function(o,n,r,t){gform.addHook(\"filter\",o,n,r,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,n){gform.removeHook(\"action\",o,n)},removeFilter:function(o,n,r){gform.removeHook(\"filter\",o,n,r)},addHook:function(o,n,r,t,i){null==gform.hooks[o][n]&&(gform.hooks[o][n]=[]);var e=gform.hooks[o][n];null==i&&(i=n+\"_\"+e.length),gform.hooks[o][n].push({tag:i,callable:r,priority:t=null==t?10:t})},doHook:function(n,o,r){var t;if(r=Array.prototype.slice.call(r,1),null!=gform.hooks[n][o]&&((o=gform.hooks[n][o]).sort(function(o,n){return o.priority-n.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==n?t.apply(null,r):r[0]=t.apply(null,r)})),\"filter\"==n)return r[0]},removeHook:function(o,n,t,i){var r;null!=gform.hooks[o][n]&&(r=(r=gform.hooks[o][n]).filter(function(o,n,r){return!!(null!=i&&i!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][n]=r)}});<\/script>\n                <div class='gf_browser_gecko gform_wrapper gravity-theme' id='gform_wrapper_11' >\n                        <div class='gform_heading'>\n                            <span class='gform_description'><\/span>\n                        <\/div><form method='post' enctype='multipart\/form-data'  id='gform_11'  action='\/fr\/wp-json\/wp\/v2\/pages\/710' data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/pages\/710\" >\n                        <div class='gform_body gform-body'><div id='gform_fields_11' class='gform_fields top_label form_sublabel_below description_below'><fieldset id=\"field_11_1\" class=\"gfield gfield_contains_required field_sublabel_below field_description_below gfield_visibility_visible\" ><legend class='gfield_label gfield_label_before_complex'  >nom<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_complex ginput_container no_prefix has_first_name no_middle_name has_last_name no_suffix gf_name_has_2 ginput_container_name' id='input_11_1'>\n                            \n                            <span id='input_11_1_3_container' class='name_first' >\n                                                    <input type='text' name='input_1.3' id='input_11_1_3' value=''   aria-required='true'     \/>\n                                                    <label for='input_11_1_3' >nom<\/label>\n                                                <\/span>\n                            \n                            <span id='input_11_1_6_container' class='name_last' >\n                                                    <input type='text' name='input_1.6' id='input_11_1_6' value=''   aria-required='true'     \/>\n                                                    <label for='input_11_1_6' >Noms de famille<\/label>\n                                                <\/span>\n                            \n                        <\/div><\/fieldset><div id=\"field_11_2\" class=\"gfield gfield--width-full gfield_contains_required field_sublabel_below field_description_below gfield_visibility_visible\" ><label class='gfield_label' for='input_11_2' >Courrier \u00e9lectronique<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_2' id='input_11_2' type='text' value='' class='large'    aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><div id=\"field_11_3\" class=\"gfield gfield--width-full gfield_contains_required field_sublabel_below field_description_below gfield_visibility_visible\" ><label class='gfield_label' for='input_11_3' >T\u00e9l\u00e9phone<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/label><div class='ginput_container ginput_container_phone'><input name='input_3' id='input_11_3' type='text' value='' class='large'   aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_11_5\" class=\"gfield gfield--width-full field_sublabel_below field_description_below gfield_visibility_visible\" ><label class='gfield_label' for='input_11_5' >message<\/label><div class='ginput_container ginput_container_textarea'><textarea name='input_5' id='input_11_5' class='textarea small'      aria-invalid=\"false\"   rows='10' cols='50'><\/textarea><\/div><\/div><fieldset id=\"field_11_4\" class=\"gfield gfield--width-full gfield_contains_required field_sublabel_below field_description_below gfield_visibility_visible\" ><legend class='gfield_label gfield_label_before_complex'  >Consentement<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_text\">(Required)<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_4.1' id='input_11_4_1' type='checkbox' value='1'   aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gfield_consent_label\" for='input_11_4_1' >J&#039;ai lu et accepte le <a href=\"https:\/\/garciamariformacion.com\/fr\/legal\/\" target=\"_blank\">mentions l\u00e9gales et politique de confidentialit\u00e9 de DENTAL GARCIA MARI SLP<\/a>.<\/label><input type='hidden' name='input_4.2' value='He le\u00eddo y acepto el &lt;a href=&quot;https:\/\/garciamariformacion.com\/legal\/&quot; target=&quot;_blank&quot;&gt;aviso legal y pol\u00edtica de privacidad de DENTAL GARCIA MARI SLP&lt;\/a&gt;.' class='gform_hidden' \/><input type='hidden' name='input_4.3' value='16' class='gform_hidden' \/><\/div><\/fieldset><\/div><\/div>\n        <div class='gform_footer top_label'> <input type='submit' id='gform_submit_button_11' class='gform_button button' value='Recevez plus d&#039;informations &gt;&gt;'  onclick='if(window[\"gf_submitting_11\"]){return false;}  window[\"gf_submitting_11\"]=true;  ' onkeypress='if( event.keyCode == 13 ){ if(window[\"gf_submitting_11\"]){return false;} window[\"gf_submitting_11\"]=true;  jQuery(\"#gform_11\").trigger(\"submit\",[true]); }' \/> \n            <input type='hidden' class='gform_hidden' name='is_submit_11' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='11' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_11' value='WyJ7XCI0LjFcIjpcIjdmYmEwYTM5MTBhZjAyZjAzZjI1MGFhOTEzZmUxNTNlXCIsXCI0LjJcIjpcImVlYjVlMTc5ODdmMGFlNDNiNGI4MDYwODljZmE4OTMyXCIsXCI0LjNcIjpcImU1ZjNjN2YzMTBiMzEwY2M5Zjc1NmM0OTEyZmYwMmYwXCJ9IiwiMWViMTY0YmQ5ZWNkMzE5OWRlNzIyMTFlMDZiMmQyNzQiXQ==' \/>\n            <input type='hidden' class='gform_hidden' name='gform_target_page_number_11' id='gform_target_page_number_11' value='0' \/>\n            <input type='hidden' class='gform_hidden' name='gform_source_page_number_11' id='gform_source_page_number_11' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n                        <\/div>            <\/div>\n            \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Curso intensivo con pacientes: Implantes dentales, cirug\u00eda guiada y dise\u00f1o CAD-CAM En este curso eminentemente pr\u00e1ctico, realizaremos el diagn\u00f3stico y la planificaci\u00f3n con la ayuda de herramientas de dise\u00f1o CAD-CAM. Esto nos permitir\u00e1 adentrarnos en el mundo de la cirug\u00eda guiada por ordenador. Al tratarse de un curso de iniciaci\u00f3n, se explicar\u00e1n conceptos como la [&hellip;]<\/p>","protected":false},"author":2,"featured_media":0,"parent":283,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-710","1":"page","2":"type-page","3":"status-publish","5":"entry"},"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso de implantes dentales, cirug\u00eda guiada por ordenador y dise\u00f1o CAD-CAM<\/title>\n<meta name=\"description\" content=\"Curso eminentemente pr\u00e1ctico: diagn\u00f3stico y planificaci\u00f3n con ayuda de herramientas de dise\u00f1o CAD-CAM. Curso intensivo de 6 d\u00edas de duraci\u00f3n en Tenerife.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso de implantes dentales, cirug\u00eda guiada por ordenador y dise\u00f1o CAD-CAM\" \/>\n<meta property=\"og:description\" content=\"Curso eminentemente pr\u00e1ctico: diagn\u00f3stico y planificaci\u00f3n con ayuda de herramientas de dise\u00f1o CAD-CAM. Curso intensivo de 6 d\u00edas de duraci\u00f3n en Tenerife.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/\" \/>\n<meta property=\"og:site_name\" content=\"Garc\u00eda Mar\u00ed Formaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-17T16:04:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/garciamariformacion.com\/wp-content\/uploads\/2020\/05\/Dr-Luis-Garci\u0301a-Mari\u0301.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/garciamariformacion.com\/fr\/#website\",\"url\":\"https:\/\/garciamariformacion.com\/fr\/\",\"name\":\"Garc\\u00eda Mar\\u00ed Formaci\\u00f3n\",\"description\":\"Especialistas en formaci\\u00f3n para dentistas.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/garciamariformacion.com\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/garciamariformacion.com\/wp-content\/uploads\/2020\/05\/Dr-Luis-Garci\\u0301a-Mari\\u0301.jpg\",\"width\":711,\"height\":815,\"caption\":\"Luis Garc\\u00eda Mar\\u00ed odont\\u00f3logo de la Cl\\u00ednica dental en Tenerife Garc\\u00eda Mar\\u00ed\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/#webpage\",\"url\":\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/\",\"name\":\"Curso de implantes dentales, cirug\\u00eda guiada por ordenador y dise\\u00f1o CAD-CAM\",\"isPartOf\":{\"@id\":\"https:\/\/garciamariformacion.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/#primaryimage\"},\"datePublished\":\"2020-06-18T12:12:28+00:00\",\"dateModified\":\"2021-05-17T16:04:38+00:00\",\"description\":\"Curso eminentemente pr\\u00e1ctico: diagn\\u00f3stico y planificaci\\u00f3n con ayuda de herramientas de dise\\u00f1o CAD-CAM. Curso intensivo de 6 d\\u00edas de duraci\\u00f3n en Tenerife.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/garciamariformacion.com\/fr\/profesionales\/cursos-de-odontologia\/cad-cam\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages\/710"}],"collection":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/comments?post=710"}],"version-history":[{"count":0,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages\/710\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages\/283"}],"wp:attachment":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/media?parent=710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}