{"id":3,"date":"2020-05-12T06:54:07","date_gmt":"2020-05-12T06:54:07","guid":{"rendered":"http:\/\/huertali-cp85.wordpresstemporal.com\/gmari\/?page_id=3"},"modified":"2020-10-08T07:05:24","modified_gmt":"2020-10-08T07:05:24","slug":"legal","status":"publish","type":"page","link":"https:\/\/garciamariformacion.com\/fr\/legal\/","title":{"rendered":"Mentions l\u00e9gales et politique de confidentialit\u00e9"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3\" class=\"elementor elementor-3\" data-elementor-settings=\"[]\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ce6ab1c elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ce6ab1c\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7c0a7d07\" data-id=\"7c0a7d07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-28b35b3 elementor-widget elementor-widget-heading\" data-id=\"28b35b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de confidentialit\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a4f706c elementor-widget elementor-widget-text-editor\" data-id=\"3a4f706c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<p><b>Responsable<br \/><\/b><span style=\"font-weight: 400;\">CENTRE D&#039;ESTH\u00c9TIQUE DENTAIRE INNOVA, SLP\u00a0<\/span><\/p>\n<p><b>But <br \/><\/b><span style=\"font-weight: 400;\">Attention aux demandes li\u00e9es \u00e0 la prestation de services et au respect des obligations contractuelles et pr\u00e9contractuelles.\u00a0<\/span><\/p>\n<p><b>L\u00e9gitimation<br \/><\/b><span style=\"font-weight: 400;\">Consentement de l&#039;int\u00e9ress\u00e9\u00a0<\/span><\/p>\n<p><b>Destinataires\u00a0<br \/><\/b><span style=\"font-weight: 400;\">Autres entreprises espagnoles affili\u00e9es au r\u00e9seau d&#039;entit\u00e9s collaboratrices du CENTRO EST\u00c9TICO DENTAL INNOVA, SLP Administrations et organismes publics pour l&#039;accomplissement des obligations directement payables au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP\u00a0<\/span><\/p>\n<p><b>Droits <\/b><span style=\"font-weight: 400;\">Acc\u00e9der, rectifier et supprimer des donn\u00e9es, ainsi que d&#039;autres\u00a0<\/span><span style=\"font-weight: 400;\">droits, comme expliqu\u00e9 dans les informations compl\u00e9mentaires\u00a0<\/span><\/p>\n<p><b>Information compl\u00e9mentaire\u00a0<\/b><b><br \/><\/b><span style=\"font-weight: 400;\">CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, dans son engagement envers la protection des donn\u00e9es personnelles de ses clients, et en tant que garant maximum de leur vie priv\u00e9e, a proc\u00e9d\u00e9 \u00e0 une r\u00e9vision de tous ses processus commerciaux et en particulier ceux qui impliquent le traitement de donn\u00e9es personnelles, en les adaptant aux nouvelles exigences de la r\u00e9glementation communautaire, le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD), a mis en \u0153uvre les mesures de s\u00e9curit\u00e9 appropri\u00e9es sur la base des r\u00e9sultats obtenus \u00e0 partir de l&#039;analyse des risques r\u00e9alis\u00e9e et a mis \u00e0 jour ses politiques de confidentialit\u00e9 et par cons\u00e9quent le pr\u00e9sent Avis L\u00e9gal.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou Client garantit que les donn\u00e9es fournies sont v\u00e9ridiques, exactes, compl\u00e8tes et mises \u00e0 jour, et est responsable de tout dommage ou perte, direct ou indirect, qui pourrait r\u00e9sulter du non-respect de cette obligation. Dans le cas o\u00f9 les donn\u00e9es fournies appartiennent \u00e0 un tiers, l&#039;Utilisateur et\/ou le Client garantit avoir inform\u00e9 ledit tiers des aspects contenus dans ce document et obtenu son autorisation pour fournir ses donn\u00e9es au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP pour les finalit\u00e9s d\u00e9clar\u00e9es.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le portail peut h\u00e9berger des blogs, des forums et d&#039;autres applications ou services de r\u00e9seaux sociaux dans le but de faciliter l&#039;\u00e9change de connaissances et de contenus. Toute information personnelle fournie par l&#039;utilisateur peut \u00eatre partag\u00e9e avec d&#039;autres utilisateurs de ce service, sur lesquels CENTRO EST\u00c9TICO DENTAL INNOVA, SLP n&#039;a aucun contr\u00f4le.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c0 des fins de s\u00e9curit\u00e9 technique et de diagnostic du syst\u00e8me, de mani\u00e8re anonymis\u00e9e ou pseudonymis\u00e9e, CENTRO EST\u00c9TICO DENTAL INNOVA, SLP peut enregistrer l&#039;adresse IP (num\u00e9ro d&#039;identification de l&#039;acc\u00e8s Internet de l&#039;appareil, qui permet aux appareils, syst\u00e8mes et serveurs de reconna\u00eetre et de communiquer). l&#039;un l&#039;autre). Ces informations peuvent \u00e9galement \u00eatre utilis\u00e9es \u00e0 des fins d\u2019analyse des performances Web.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conform\u00e9ment aux dispositions de la r\u00e9glementation applicable en mati\u00e8re de protection des donn\u00e9es personnelles, l&#039;Utilisateur et\/ou Client de CENTRO EST\u00c9TICO DENTAL INNOVA, SLP est inform\u00e9 de ce qui suit :\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>1. RESPONSABLE DU TRAITEMENT\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Les entit\u00e9s suivantes appartiennent au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, et donc responsables du traitement des donn\u00e9es fournies volontairement par l&#039;utilisateur\u00a0:\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">CENTRE ESTH\u00c9TIQUE DENTAIRE INNOVA, SLP CIF : B38945200 <\/span><\/li>\n<\/ul>\n<h3><span style=\"color: #172983;\"><b>2. Finalit\u00e9s du traitement des donn\u00e9es personnelles\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles fournies volontairement par l&#039;utilisateur, soit en remplissant des formulaires - sur papier ou \u00e9lectroniques -, soit par des communications par courrier \u00e9lectronique ou par contact t\u00e9l\u00e9phonique, seront incorpor\u00e9es dans les dossiers de traitement appartenant \u00e0 l&#039;utilisateur. du CENTRO EST\u00c9TICO DENTAL INNOVA , SLP ou les soci\u00e9t\u00e9s qui composent le Groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP aux fins suivantes\u00a0:\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Le traitement et la gestion de la demande d&#039;information et\/ou de conseil, d&#039;avant-contrat ou de contrat formul\u00e9e par l&#039;Utilisateur et\/ou Client \u00e0 travers ce site, t\u00e9l\u00e9phone, email.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La gestion et le contr\u00f4le des services offerts via le site Web, par t\u00e9l\u00e9phone ou par courrier \u00e9lectronique, li\u00e9s aux conseils et \u00e0 la fourniture de services pouvant n\u00e9cessiter une r\u00e9f\u00e9rence \u00e0 des professionnels dans le domaine juridique, de la sant\u00e9 et des assurances.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Envoi d&#039;informations sur les services et produits du CENTRO EST\u00c9TICO DENTAL INNOVA, SLP et du Groupe de filiales, dont la souscription peut int\u00e9resser l&#039;utilisateur.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Fournir un soutien juridique aux groupes d\u00e9favoris\u00e9s, en r\u00e9alisant des activit\u00e9s li\u00e9es \u00e0 la formation, \u00e0 la sensibilisation et au d\u00e9veloppement de programmes et de projets sp\u00e9cifiques \u00e0 l&#039;entrepreneuriat.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">G\u00e9rer les Utilisateurs du Site Web et, le cas \u00e9ch\u00e9ant, l&#039;activation et l&#039;administration de l&#039;inscription en tant qu&#039;Utilisateur dans la zone r\u00e9serv\u00e9e du Site Web.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Fournir les services inclus dans le site Web et\/ou fournir les informations demand\u00e9es, que ce soit via le Web, par courrier \u00e9lectronique ou par t\u00e9l\u00e9phone. Les appels t\u00e9l\u00e9phoniques peuvent \u00eatre enregistr\u00e9s afin de garantir la qualit\u00e9 du service. Les emails peuvent faire \u00e9tat d&#039;une confirmation de leur r\u00e9ception et de leur lecture.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">G\u00e9rer la relation contractuelle ou commerciale \u00e9tablie entre CENTRO EST\u00c9TICO DENTAL INNOVA, SLP et les Utilisateurs et\/ou Clients.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">G\u00e9rer le respect des obligations contractuelles ou extracontractuelles assum\u00e9es par CENTRO EST\u00c9TICO DENTAL INNOVA, SLP\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">G\u00e9rer et maintenir un registre unique des clients des entreprises du Groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, dans le syst\u00e8me promotionnel du CENTRO EST\u00c9TICO DENTAL INNOVA, SLP\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Proposer \u00e0 l&#039;Utilisateur des produits et services ou des contenus personnalis\u00e9s en obtenant des profils et des t\u00e2ches de segmentation ou CRM, en \u00e9largissant et en am\u00e9liorant ceux dont dispose actuellement le Client.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Dans les cas o\u00f9 l&#039;Utilisateur consent express\u00e9ment, envoyer des communications publicitaires et des informations commerciales, par diff\u00e9rents moyens (e-mails, SMS, re\u00e7u d&#039;achat...), sur CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, de la part des entit\u00e9s du Groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP ou des tiers (toujours par l&#039;interm\u00e9diaire du CENTRO EST\u00c9TICO DENTAL INNOVA, SLP elle-m\u00eame, en cons\u00e9quence de ses accords de collaboration avec eux), sur ses activit\u00e9s, produits, services, offres, concours, promotions sp\u00e9ciales, ainsi que la documentation de nature diverse qui peut \u00eatre int\u00e9ressant ou utile \u00e0 l&#039;Utilisateur et\/ou au Client, li\u00e9 aux secteurs du transport, des loisirs, du voyage, de la culture, des cartes et moyens de paiement, de l&#039;automobile, de l&#039;assurance, du financement, des cadeaux ou de la technologie.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">De m\u00eame, dans chaque processus au cours duquel l&#039;utilisateur fournit ses donn\u00e9es personnelles, il sera inform\u00e9 du caract\u00e8re obligatoire ou facultatif de leur compl\u00e9tion et des cons\u00e9quences de leur non-fourniture.\u00a0<\/span><\/p>\n<h3><b><span style=\"color: #172983;\">3. INFORMATIONS SUR LE TRAITEMENT DES DONN\u00c9ES POUR L&#039;ENVOI DE COMMUNICATIONS<\/span>\u00a0<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es utilis\u00e9es ou fournies dans des communications informatives et\/ou promotionnelles sont trait\u00e9es par CENTRO EST\u00c9TICO DENTAL INNOVA, SLP \u00e0 des fins consistant \u00e0 envoyer des communications \u00e9lectroniques \u00e0 caract\u00e8re informatif sur les services, activit\u00e9s, publications, c\u00e9l\u00e9brations, f\u00e9licitations et \u00e9v\u00e9nements sociaux et professionnels de CENTRO EST\u00c9TICO DENTAL INNOVA, SLP ou des tiers du r\u00e9seau CENTRO EST\u00c9TICO DENTAL INNOVA, SLP de cabinets du secteur, conseils et assurances susceptibles d&#039;int\u00e9resser l&#039;Utilisateur et\/ou le Client\u00a0; le suivi et l&#039;optimisation des campagnes marketing r\u00e9alis\u00e9es \u00e0 l&#039;aide de technologies pr\u00e9vues \u00e0 cet effet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le consentement \u00e0 l&#039;envoi desdites communications peut \u00eatre r\u00e9voqu\u00e9 \u00e0 tout moment dans chacune des communications re\u00e7ues via le m\u00e9canisme activ\u00e9 \u00e0 cet effet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le crit\u00e8re de conservation des donn\u00e9es sera bas\u00e9 sur la d\u00e9claration contre le traitement de votre part. Dans tous les cas, les droits d&#039;acc\u00e8s, de rectification, de suppression, de limitation du traitement, d&#039;opposition, de portabilit\u00e9 et de ne pas faire l&#039;objet de d\u00e9cisions individuelles automatis\u00e9es pourront \u00eatre exerc\u00e9s par courrier \u00e9lectronique \u00e0 <\/span><b>cedgarciamari@gmail.com <\/b><span style=\"font-weight: 400;\">en joignant une photocopie du DNI ou un document \u00e9quivalent.\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>4. DONN\u00c9ES PERSONNELLES DE TIERS\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Dans le cas o\u00f9 les donn\u00e9es personnelles fournies par une personne autre que l&#039;utilisateur ou le propri\u00e9taire des donn\u00e9es agissant en qualit\u00e9 de repr\u00e9sentant, ledit repr\u00e9sentant garantit qu&#039;il a inform\u00e9 le propri\u00e9taire des donn\u00e9es qu&#039;il fournit de la pr\u00e9sente politique de confidentialit\u00e9 et qu&#039;il a obtenu son autorisation de fournir vos donn\u00e9es au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP avec le\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">finalit\u00e9s d\u00e9clar\u00e9es. Il garantit \u00e9galement que les donn\u00e9es fournies sont exactes et \u00e0 jour et est responsable de tout dommage ou perte, direct ou indirect, qui pourrait r\u00e9sulter du non-respect de cette obligation.\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>5. DUR\u00c9E DE CONSERVATION DES DONN\u00c9ES PERSONNELLES\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles fournies seront conserv\u00e9es aussi longtemps que la relation contractuelle est maintenue, leur suppression n&#039;est pas demand\u00e9e par l&#039;int\u00e9ress\u00e9 et elles ne doivent pas \u00eatre supprim\u00e9es car elles sont n\u00e9cessaires au respect d&#039;une obligation l\u00e9gale, \u00e0 la formulation, \u00e0 l&#039;exercice et \u00e0 la d\u00e9fense de r\u00e9clamations, ou lorsque n\u00e9cessite sa conservation pour permettre l&#039;application de tout avantage, remise ou avantage promotionnel pour le client.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En caso de que el usuario de su consentimiento al tratamiento de sus datos o ejercite los derechos de cancelaci\u00f3n o supresi\u00f3n, sus datos personales se conservar\u00e1n bloqueados a disposici\u00f3n de la Administraci\u00f3n de Justicia durante los plazos establecidos legalmente para atender a las posibles responsabilidades nacidas del tratamiento les m\u00eames.\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>6. L\u00c9GITIMATION DU TRAITEMENT DES DONN\u00c9ES PERSONNELLES\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">CENTRO EST\u00c9TICO DENTAL INNOVA, SLP est en droit d&#039;effectuer le traitement des donn\u00e9es personnelles sur la base que\u00a0:\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou le Client a donn\u00e9 son consentement explicite pour les finalit\u00e9s d\u00e9crites \u00e0 l&#039;article 2 de la pr\u00e9sente Politique qui n\u00e9cessitent le traitement de donn\u00e9es de l&#039;Utilisateur et\/ou du Client r\u00e9v\u00e9lant l&#039;origine ethnique ou raciale, les opinions politiques, les convictions religieuses ou philosophiques, l&#039;appartenance syndicale, les donn\u00e9es g\u00e9n\u00e9tiques, les donn\u00e9es biom\u00e9triques visant \u00e0 identifier de mani\u00e8re unique une personne physique, les donn\u00e9es relatives \u00e0 la sant\u00e9, aux infractions p\u00e9nales ou aux donn\u00e9es relatives \u00e0 la vie ou \u00e0 l&#039;orientation sexuelle.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou Client a fourni ses donn\u00e9es personnelles dans le cadre d&#039;une relation contractuelle ou pr\u00e9contractuelle pour r\u00e9pondre \u00e0 sa demande d&#039;information et\/ou de conseil dans le domaine de l&#039;assistance juridique, de sant\u00e9 et d&#039;assurance.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou Client a donn\u00e9 son consentement \u00e9clair\u00e9 pour l&#039;envoi de communications commerciales li\u00e9es aux produits et\/ou services de CENTRO EST\u00c9TICO DENTAL INNOVA, SLP susceptibles d&#039;int\u00e9resser l&#039;Utilisateur et\/ou Client, pour l&#039;installation de syst\u00e8mes de suivi. .qui rapportent les habitudes de navigation conform\u00e9ment \u00e0 la politique de cookies, ou pour envoyer les informations requises via les formulaires de contact.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Il existe des obligations l\u00e9gales qui n\u00e9cessitent le traitement des donn\u00e9es personnelles, conform\u00e9ment aux services fournis.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La base juridique du traitement des donn\u00e9es personnelles des Utilisateurs et\/ou Clients par CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, r\u00e9side dans les lettres a), b) et c) du num\u00e9ro 1 de l&#039;article 6 du R\u00e8glement (UE) 2016\/679, avril. 27.\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>7. CAT\u00c9GORIES DE DESTINATAIRES\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Les donn\u00e9es personnelles des Utilisateurs et\/ou Clients du CENTRO EST\u00c9TICO DENTAL INNOVA, SLP pourront \u00eatre communiqu\u00e9es aux cat\u00e9gories d\u2019int\u00e9ress\u00e9s suivantes :\u00a0<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Agences avec lesquelles les soci\u00e9t\u00e9s du Groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP ont des accords de collaboration pour permettre l&#039;ex\u00e9cution et la bonne ex\u00e9cution du contrat.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Entit\u00e9s d&#039;assurance avec lesquelles les soci\u00e9t\u00e9s du groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP ont des accords de collaboration pour permettre l&#039;ex\u00e9cution et la correcte conformit\u00e9 du contrat d&#039;assurance.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Les soci\u00e9t\u00e9s du Groupe CENTRO EST\u00c9TICO DENTAL INNOVA, SLP\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Fournisseurs de services informatiques, y compris les services de \u00ab cloud computing \u00bb.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Les Administrations et Organismes Publics, pour l&#039;accomplissement des obligations directement payables au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP et\/ou lorsque l&#039;autorisation l\u00e9gale correspondante existe.\u00a0<\/span><\/li>\n<\/ul>\n<h3><span style=\"color: #172983;\"><b>8. TRANSFERTS INTERNATIONAUX\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Actuellement, CENTRO EST\u00c9TICO DENTAL INNOVA, SLP n&#039;effectue pas de transferts internationaux de donn\u00e9es.\u00a0<\/span><\/p>\n<h3><b><span style=\"color: #172983;\">9. DROITS DES PARTIES INT\u00c9RESS\u00c9ES\u00a0<\/span><\/b><\/h3>\n<p><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou le Client peuvent exercer aupr\u00e8s de CENTRO EST\u00c9TICO DENTAL INNOVA, SLP les droits d&#039;acc\u00e8s, de rectification, de suppression, de limitation du traitement, d&#039;opposition, de portabilit\u00e9 et de s&#039;opposer aux d\u00e9cisions individuelles automatis\u00e9es.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De m\u00eame, ils pourront r\u00e9voquer leur consentement s\u2019ils l\u2019ont accord\u00e9 dans un but pr\u00e9cis, et modifier leurs pr\u00e9f\u00e9rences \u00e0 tout moment.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou le Client peuvent exercer l&#039;un des droits signal\u00e9s dans le paragraphe pr\u00e9c\u00e9dent, en envoyant un e-mail indiquant le droit exerc\u00e9 adress\u00e9 au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP adresse : cedgarciamari@gmail.com ou en envoyant une lettre sign\u00e9e adress\u00e9e au CENTRO EST\u00c9TICO DENTAL INNOVA, SLP, Prolongaci\u00f3n Ram\u00f3n y Cajal 13 Local 4, 38003, Santa Cruz de Tenerife, en joignant dans les deux cas une copie du DNI, NIE ou passeport et les documents qui, le cas \u00e9ch\u00e9ant, justifient la demande.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&#039;Utilisateur et\/ou Client est inform\u00e9 qu&#039;il peut adresser tout type de r\u00e9clamation concernant la protection des donn\u00e9es personnelles \u00e0 l&#039;Agence espagnole de protection des donn\u00e9es www.agpd.es, Autorit\u00e9 de contr\u00f4le de l&#039;\u00c9tat espagnol.\u00a0<\/span><\/p>\n<h3><span style=\"color: #172983;\"><b>10. MISE \u00c0 JOUR DE LA POLITIQUE\u00a0<\/b><\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Cette politique a \u00e9t\u00e9 mise \u00e0 jour conform\u00e9ment aux exigences de la r\u00e9glementation communautaire sur la protection des donn\u00e9es personnelles, le R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De m\u00eame, il est signal\u00e9 que cette politique peut \u00eatre modifi\u00e9e en raison de changements dans les exigences \u00e9tablies par la l\u00e9gislation en vigueur \u00e0 tout moment, par des d\u00e9cisions judiciaires et des changements jurisprudentiels, ainsi que par des changements dans les actions et la strat\u00e9gie commerciale du CENTRO EST\u00c9TICO DENTAL INNOVA. , SLP et ses filiales. La publication et l&#039;acc\u00e8s des utilisateurs s&#039;effectueront \u00e0 travers ce m\u00eame site, \u00e9tant entendu que les relations \u00e9tablies avec eux avant le changement seront r\u00e9gies par les r\u00e8gles \u00e9tablies au moment de l&#039;acc\u00e8s au site pour sa cr\u00e9ation.\u00a0<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2904f43 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2904f43\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2c5bacf\" data-id=\"2c5bacf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b6cce2 elementor-widget elementor-widget-heading\" data-id=\"6b6cce2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de cookies<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a92c7 elementor-widget elementor-widget-text-editor\" data-id=\"60a92c7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<p>Nous vous informons que sur ce site Internet, nous utilisons des cookies afin de faciliter l&#039;utilisation et la navigation sur le site Internet, ainsi que d&#039;\u00e9tablir des statistiques d&#039;utilisation de notre site Internet.<\/p><h3><b>Que sont les cookies ?<\/b><\/h3><p>Les cookies sont de petits fichiers de donn\u00e9es qui sont g\u00e9n\u00e9r\u00e9s sur l&#039;ordinateur, le smartphone, la tablette ou tout autre appareil de l&#039;utilisateur lors de l&#039;acc\u00e8s \u00e0 un site Web et qui permettent au propri\u00e9taire de ladite page de stocker ou de r\u00e9cup\u00e9rer certaines informations sur la navigation effectu\u00e9e \u00e0 partir dudit \u00e9quipement.<\/p><h3>Cookies utilis\u00e9s sur ce site<\/h3>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3362621 elementor-widget elementor-widget-text-editor\" data-id=\"3362621\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<p>\u00e0)<strong> Cookies techniques pour m\u00e9moriser les pr\u00e9f\u00e9rences de confidentialit\u00e9.<\/strong><\/p><ul><li><strong><em>\u00a0Cookie borlabscookie<\/em><\/strong><ul><li>D\u00e9lai d&#039;expiration 1 an<\/li><li>Cookie technique<\/li><li>Il sert \u00e0 m\u00e9moriser vos pr\u00e9f\u00e9rences en mati\u00e8re de confidentialit\u00e9 concernant les cookies sur le site Web.<\/li><\/ul><\/li><li><strong><em>Cookie borlabsCookieUnblockContent<\/em><\/strong><ul><li>D\u00e9lai d&#039;expiration 1 an<\/li><li>Cookie technique<\/li><li>Il sert \u00e0 vous rappeler votre choix de d\u00e9bloquer certains contenus du site Internet qui ne pourraient \u00eatre affich\u00e9s que si vous acceptiez explicitement la politique de confidentialit\u00e9.<\/li><\/ul><\/li><\/ul><p><strong>b) Cookies techniques WordPress<\/strong><\/p><ul><li><strong><em>Cookie wordpress_test_cookie<\/em><\/strong><ul><li>Cookie de session<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie est utilis\u00e9 par le gestionnaire de contenu WordPress pour v\u00e9rifier si le navigateur a activ\u00e9 les cookies.<\/li><\/ul><\/li><li><strong><em>Cookie wp-settings-2<\/em><\/strong><ul><li>D\u00e9lai d&#039;expiration dans 1 an<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie est utilis\u00e9 pour personnaliser l&#039;interface utilisateur<\/li><\/ul><\/li><li><em><strong>Cookie wp-settings-time-2<\/strong><\/em><ul><li>D\u00e9lai d&#039;expiration dans 1 an<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie est utilis\u00e9 pour personnaliser l&#039;interface utilisateur<\/li><\/ul><\/li><li><em><strong>Cookie wordpress_logged_in_[hash]<\/strong><\/em><ul><li>Cookie de session<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie est utilis\u00e9 dans le but de reconna\u00eetre un administrateur ou un utilisateur connect\u00e9 dans la base de donn\u00e9es du site Web lorsqu&#039;il se connecte, de savoir qui il est et d&#039;afficher son interface utilisateur respective au sein du syst\u00e8me.<\/li><\/ul><\/li><li><em><strong>Cookie wordpress_[hash]<\/strong><\/em><ul><li>Cookie de session<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie a un usage limit\u00e9 pour la zone d&#039;administration \/wp-admin\/ \u00e0 laquelle seuls les administrateurs ou les utilisateurs connect\u00e9s ont acc\u00e8s.\u00a0<\/li><\/ul><\/li><li><em><strong>Cookie wordpress_sec_[hash]<\/strong><\/em><ul><li>Cookie de session<\/li><li>Cookie utilis\u00e9 par WordPress<\/li><li>Ce cookie est utilis\u00e9 dans les entr\u00e9es du panneau d&#039;administration WordPress pour authentifier les connexions SSL.<\/li><\/ul><\/li><li><em><strong>Cookie PHPSESSID<\/strong><\/em><ul><li>Cookie de session<\/li><li>Ce cookie est utilis\u00e9 par le langage de cryptage PHP pour permettre l&#039;enregistrement des variables SESSION sur le serveur web. Ces cookies sont indispensables au fonctionnement du site Internet.<\/li><\/ul><\/li><\/ul><p><strong>c) Cookies techniques des passerelles de paiement pour effectuer des paiements sur le Web<\/strong><\/p><ul><li>Cookie __stripe_mid<ul><li>D\u00e9lai d&#039;expiration 1 semaine<\/li><li>Cookie utilis\u00e9 par la passerelle de paiement Stripe<\/li><li>Stripe utilise un cookie pour permettre au site Web de traiter les paiements sans stocker aucune information de carte de cr\u00e9dit sur ses propres serveurs.<\/li><\/ul><\/li><li>Cookie __stripe_sid<ul><li>D\u00e9lai d&#039;expiration 1 jour<\/li><li>Cookie utilis\u00e9 par la passerelle de paiement Stripe<\/li><li>Stripe utilise un cookie pour permettre au site Web de traiter les paiements sans stocker aucune information de carte de cr\u00e9dit sur ses propres serveurs.<\/li><\/ul><\/li><\/ul><p><strong>d) Cookies Google pouvant \u00eatre activ\u00e9s lors du visionnage d&#039;une vid\u00e9o YouTube ou GoogleMaps<\/strong><\/p><ul><li><em><strong>PR\u00c9F\u00c9RENCE DES Cookies<\/strong><\/em><ul><li>D\u00e9lai d&#039;expiration 2 ans<\/li><li>Cookie tiers de YouTube.com qui sera activ\u00e9 lors de la lecture d&#039;une vid\u00e9o YouTube int\u00e9gr\u00e9e sur notre site Web.<\/li><li>Lorsque vous cr\u00e9ez ou vous connectez \u00e0 un compte Google, ce cookie est stock\u00e9 sur votre ordinateur afin de rester connect\u00e9 \u00e0 votre compte Google lorsque vous visitez \u00e0 nouveau ses services. Tant que vous restez connect\u00e9 et utilisez des plugins sur d&#039;autres sites Web comme le n\u00f4tre, Google utilisera ces cookies pour am\u00e9liorer votre exp\u00e9rience utilisateur.<\/li><\/ul><\/li><li><em><strong>VISITOR_INFO1_LIVECookie<\/strong><\/em><ul><li>D\u00e9lai d&#039;expiration 2 ans<\/li><li>Cookie tiers de YouTube.com qui sera activ\u00e9 lors de la lecture d&#039;une vid\u00e9o YouTube int\u00e9gr\u00e9e sur notre site Web.<\/li><li>Les vid\u00e9os YouTube avec la m\u00e9thode d&#039;am\u00e9lioration de la confidentialit\u00e9 activ\u00e9e sont int\u00e9gr\u00e9es sur le site Web. Cela peut entra\u00eener l&#039;envoi de cookies \u00e0 votre navigateur une fois que vous cliquez dessus, mais YouTube ne stockera aucune information personnelle ou identifiable.<\/li><\/ul><\/li><li><em><strong>Cookie test_cookie<\/strong><\/em><ul><li>Temps d&#039;expiration 30 minutes. Ce cookie est activ\u00e9 si vous visionnez une vid\u00e9o YouTube sur notre page.<\/li><li>Cookie utilis\u00e9 par doubleclick.net<\/li><li>Ce cookie v\u00e9rifie si un utilisateur ne dispose pas d&#039;un cookie double-clic, et si c&#039;est le cas, un cookie est d\u00e9pos\u00e9 pour v\u00e9rifier si son navigateur les accepte.<\/li><\/ul><\/li><li><em><strong>Cookie YSC<\/strong><\/em><ul><li>Cookie de session<\/li><li>Cookie tiers de YouTube.com qui sera activ\u00e9 lors de la lecture d&#039;une vid\u00e9o YouTube int\u00e9gr\u00e9e sur notre site Web.<\/li><li>Cookie qui mesure les vues vid\u00e9o r\u00e9alis\u00e9es par l&#039;utilisateur et enregistre les \u00e9v\u00e9nements \u00ab J&#039;aime \u00bb ou \u00ab Partager la vid\u00e9o \u00bb. Il s&#039;agit d&#039;un cookie de session, qui expire \u00e0 la fin de la session avec le navigateur.<\/li><\/ul><\/li><li><em><strong>NID de cookie<\/strong><\/em><ul><li>Cookie tiers de Google qui sera activ\u00e9 lors de l&#039;acc\u00e8s \u00e0 une section du site Web dans laquelle une carte Google Maps est int\u00e9gr\u00e9e<\/li><li>Le cookie NID contient un identifiant unique que Google utilise pour m\u00e9moriser vos pr\u00e9f\u00e9rences et d&#039;autres informations, telles que votre langue pr\u00e9f\u00e9r\u00e9e (par exemple, l&#039;espagnol), le nombre de r\u00e9sultats de recherche que vous souhaitez afficher par page (par exemple, 10 ou 20) et si vous souhaitez que le filtre SafeSearch de Google soit activ\u00e9 ou d\u00e9sactiv\u00e9.<\/li><\/ul><\/li><\/ul><p><!-- wp:paragraph --><\/p><p><strong>e) Cookies publicitaires Facebook (utilis\u00e9s uniquement lorsque l&#039;utilisateur marque volontairement qu&#039;il accepte l&#039;utilisation de tous les cookies)<\/strong><\/p><p><!-- \/wp:paragraph --> <!-- wp:list --><\/p><ul><li><em><strong>Cookie fr<\/strong><\/em><ul><li>D\u00e9lai d&#039;expiration : 3 mois<\/li><li>Cookie utilis\u00e9 par Facebook<\/li><li>Cookie utilis\u00e9 par Facebook pour fournir une s\u00e9rie de produits publicitaires tels que les ench\u00e8res en temps r\u00e9el d&#039;annonceurs tiers.<\/li><\/ul><\/li><li><em><strong>Cookie _fbp<\/strong><\/em><ul><li>D\u00e9lai d&#039;expiration 3 mois<\/li><li>Cookie utilis\u00e9 par Facebook<\/li><li>Cookie utilis\u00e9 par Facebook pour fournir une s\u00e9rie de produits publicitaires tels que les ench\u00e8res en temps r\u00e9el d&#039;annonceurs tiers.<\/li><\/ul><\/li><\/ul><p><!-- \/wp:list --><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7da0d25 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7da0d25\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64e45ef\" data-id=\"64e45ef\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b472155 elementor-widget elementor-widget-text-editor\" data-id=\"b472155\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t\t<h2><strong>Gestion des cookies<\/strong><\/h2><p>Vous pouvez autoriser, bloquer ou supprimer les cookies install\u00e9s sur votre ordinateur en configurant les options de votre navigateur Internet. Si vous n&#039;autorisez pas l&#039;installation de cookies dans votre navigateur, vous ne pourrez peut-\u00eatre pas acc\u00e9der \u00e0 certains services et votre exp\u00e9rience sur notre site Web pourra \u00eatre moins satisfaisante.<\/p><p>Dans les liens ci-dessous, vous pouvez trouver plus d&#039;informations pour configurer ou d\u00e9sactiver les cookies dans chaque navigateur :<\/p><p>\u00e0.<a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?hl=es\">\u00a0Google Chrome<\/a>.<br \/>b.\u00a0<a href=\"https:\/\/support.mozilla.org\/es\/kb\/habilitar-y-deshabilitar-cookies-sitios-web-rastrear-preferencias?redirectlocale=es&amp;redirectslug=habilitar-y-deshabilitar-cookies-que-los-sitios-we\">Mozilla Firefox<\/a>.<br \/>c.\u00a0<a href=\"https:\/\/support.microsoft.com\/es-es\/help\/17442\/windows-internet-explorer-delete-manage-cookies\">Internet Explorer<\/a>.<br \/>d.\u00a0<a href=\"https:\/\/support.microsoft.com\/es-es\/help\/4468242\/microsoft-edge-browsing-data-and-privacy\">Microsoft Bord<\/a>.<br \/>et.\u00a0<a href=\"https:\/\/support.apple.com\/es-es\/guide\/safari\/sfri11471\/mac\">Safari<\/a>.<br \/>F.\u00a0<a href=\"https:\/\/support.apple.com\/es-es\/HT201265\">Safari pour IOS (iPhone et iPad)<\/a>.<br \/>g.\u00a0<a href=\"https:\/\/support.google.com\/chrome\/answer\/114662?hl=es&amp;visit_id=637209125095404118-1240899571&amp;rd=1\">Chrome pour Android<\/a>.<\/p><p>Vous devez savoir que certains des cookies inclus dans les cat\u00e9gories de cookies d\u00e9crites ci-dessus sont stock\u00e9s par des tiers sur votre ordinateur lorsque l&#039;utilisateur utilise notre site Internet. Nous n&#039;avons aucun contr\u00f4le sur ces cookies ni sur la mani\u00e8re dont des tiers les utilisent. Ils sont utilis\u00e9s pour permettre au tiers de nous fournir un service, par exemple une analyse.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Pol\u00edtica de privacidad ResponsableCENTRO EST\u00c9TICO DENTAL INNOVA, S.L.P\u00a0 Finalidad Atenci\u00f3n de solicitudes relacionadas con la prestaci\u00f3n de servicios y cumplimiento de obligaciones contractuales y precontractuales.\u00a0 Legitimaci\u00f3nConsentimiento del interesado\u00a0 Destinatarios\u00a0Otras empresas espa\u00f1olas afiliadas a la red de Entidades Colaboradoras de CENTRO EST\u00c9TICO DENTAL INNOVA, S.L.P Administraciones y organismos p\u00fablicos para el cumplimiento de obligaciones directamente exigibles [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"class_list":{"0":"post-3","1":"page","2":"type-page","3":"status-publish","5":"entry"},"aioseo_notices":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aviso legal y pol\u00edtica de privacidad - Garc\u00eda Mar\u00ed Formaci\u00f3n<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal y pol\u00edtica de privacidad - Garc\u00eda Mar\u00ed Formaci\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de privacidad ResponsableCENTRO EST\u00c9TICO DENTAL INNOVA, S.L.P\u00a0 Finalidad Atenci\u00f3n de solicitudes relacionadas con la prestaci\u00f3n de servicios y cumplimiento de obligaciones contractuales y precontractuales.\u00a0 Legitimaci\u00f3nConsentimiento del interesado\u00a0 Destinatarios\u00a0Otras empresas espa\u00f1olas afiliadas a la red de Entidades Colaboradoras de CENTRO EST\u00c9TICO DENTAL INNOVA, S.L.P Administraciones y organismos p\u00fablicos para el cumplimiento de obligaciones directamente exigibles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/garciamariformacion.com\/fr\/legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Garc\u00eda Mar\u00ed Formaci\u00f3n\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-08T07:05:24+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/garciamariformacion.com\/fr\/#website\",\"url\":\"https:\/\/garciamariformacion.com\/fr\/\",\"name\":\"Garc\\u00eda Mar\\u00ed Formaci\\u00f3n\",\"description\":\"Especialistas en formaci\\u00f3n para dentistas.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/garciamariformacion.com\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/garciamariformacion.com\/fr\/legal\/#webpage\",\"url\":\"https:\/\/garciamariformacion.com\/fr\/legal\/\",\"name\":\"Aviso legal y pol\\u00edtica de privacidad - Garc\\u00eda Mar\\u00ed Formaci\\u00f3n\",\"isPartOf\":{\"@id\":\"https:\/\/garciamariformacion.com\/fr\/#website\"},\"datePublished\":\"2020-05-12T06:54:07+00:00\",\"dateModified\":\"2020-10-08T07:05:24+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/garciamariformacion.com\/fr\/legal\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages\/3"}],"collection":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/garciamariformacion.com\/fr\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}